{"id":7234,"date":"2018-06-14T12:28:06","date_gmt":"2018-06-14T15:28:06","guid":{"rendered":"https:\/\/www.altus.com.br\/?p=7234"},"modified":"2024-09-20T10:04:46","modified_gmt":"2024-09-20T13:04:46","slug":"a-importancia-da-validacao-no-desenvolvimento-de-produtos","status":"publish","type":"post","link":"https:\/\/www.altus.com.br\/en\/post\/151\/a-importancia-da-validacao-no-desenvolvimento-de-produtos","title":{"rendered":"A import\u00e2ncia da Valida\u00e7\u00e3o no Desenvolvimento de Produtos"},"content":{"rendered":"<p>A qualidade de um produto, seja ele tang\u00edvel ou intang\u00edvel, est\u00e1 fortemente relacionada \u00e0 exist\u00eancia de n\u00e3o conformidades inseridas durante o desenvolvimento ou manuten\u00e7\u00e3o do mesmo. Uma das maneiras de identificar as n\u00e3o conformidades de um produto antes de o mesmo estar dispon\u00edvel no mercado em que ser\u00e1 inserido \u00e9 submeter o produto a um processo de valida\u00e7\u00e3o. O principal objetivo da valida\u00e7\u00e3o \u00e9 assegurar que o produto em quest\u00e3o atenda todas as caracter\u00edsticas de sua especifica\u00e7\u00e3o, identificando se est\u00e3o de acordo com as necessidades do cliente.<\/p>\n<p><b>Mas afinal, qual a fun\u00e7\u00e3o do processo de valida\u00e7\u00e3o?<\/b><\/p>\n<p>Esse processo possui a fun\u00e7\u00e3o de aprovar o produto para que o mesmo possa ser comercializado, reduzindo de forma significativa a possibilidade de um cliente final receber um produto com algum tipo de n\u00e3o-conformidade e identificar previamente os poss\u00edveis pontos cr\u00edticos que ele ir\u00e1 enfrentar perante o concorrente.<\/p>\n<p>As atividades relacionadas ao processo de valida\u00e7\u00e3o devem, preferencialmente, ser realizadas por uma equipe que n\u00e3o participe do desenvolvimento do produto, possua um olhar de cliente e esteja exclusivamente focada em identificar as n\u00e3o conformidades, sugerindo o melhor para o mercado. Devido \u00e0 sua import\u00e2ncia e sua complexidade, a valida\u00e7\u00e3o pode ser respons\u00e1vel por uma parcela consider\u00e1vel dos custos de um projeto, por isso, este assunto merece aten\u00e7\u00e3o por parte das organiza\u00e7\u00f5es que desejam sucesso no desenvolvimento de produtos.<\/p>\n<p>Um excelente planejamento de valida\u00e7\u00e3o pode significar economia para um projeto, visto que a identifica\u00e7\u00e3o de n\u00e3o conformidades no desenvolvimento do produto pode reduzir os custos de sua corre\u00e7\u00e3o posterior, al\u00e9m de melhorar sua confiabilidade.<\/p>\n<p><b>Afinal, quanto custa um problema em cliente?<\/b><\/p>\n<p>Em algumas literaturas, estima-se que o custo de um problema \u00e9 de cerca de 100 d\u00f3lares por produto instalado em cliente. Agora imagine um cen\u00e1rio com 1000 unidades instaladas. Estamos falando de no m\u00ednimo 100.000 d\u00f3lares de custo para realizar um recall em campo, al\u00e9m da imagem negativa que o produto ir\u00e1 apresentar para os seus clientes. Sendo assim, cabe um entendimento acerca do valor a ser investido nesse processo, onde encontrar a taxa de teste ideal \u00e9 o grande desafio. O intervalo da ocorr\u00eancia de detec\u00e7\u00e3o de uma n\u00e3o conformidade pode ser considerado um indicador de que o momento de encerrar os testes de valida\u00e7\u00e3o chegou ao fim e, com isto, entende-se que a ocorr\u00eancia de n\u00e3o conformidades n\u00e3o compensa mais o investimento em teste. Isto pode variar de projeto para projeto e de sua toler\u00e2ncia a falhas permitidas.<\/p>\n<p><b>Quais os principais desafios de hoje na valida\u00e7\u00e3o?<\/b><\/p>\n<p>Ao refletirmos sobre os caminhos do processo de valida\u00e7\u00e3o, precisamos ter em mente que a tecnologia tem avan\u00e7ado muito r\u00e1pido e estamos correndo para nos manter atualizados.<\/p>\n<p>Devido a esse fato, existe uma tend\u00eancia de as empresas correrem contra o tempo para lan\u00e7ar seus produtos no mercado e n\u00e3o perder a janela de oportunidades que est\u00e1 aberta no momento. Por\u00e9m, essa estrat\u00e9gia implica diretamente na valida\u00e7\u00e3o do produto, pois, como esta \u00e9 uma das \u00faltimas etapas do projeto, acaba sofrendo uma cobran\u00e7a ainda maior.<\/p>\n<p>Como um exemplo simples e pr\u00e1tico, podemos utilizar o smartphone. Quem nunca teve problemas no seu smartphone e precisou fazer uma atualiza\u00e7\u00e3o de software para resolver? As empresas que atuam nesse ramo geralmente focam sua valida\u00e7\u00e3o no projeto de hardware para depois lan\u00e7ar atualiza\u00e7\u00f5es de software corrigindo os problemas identificados por usu\u00e1rios.<\/p>\n<p>Nem todas as empresas podem realizar o processo citado anteriormente, por quest\u00f5es de seguran\u00e7a ou pela falta de recursos f\u00edsicos e financeiros. Com isso, entramos na experi\u00eancia da equipe e da base de testes especificados para serem realizados de acordo com o projeto de produto desenvolvido.<\/p>\n<p>\u00c9 importante deixar bem claro que n\u00e3o existe produto perfeito, apenas produtos que possuem menos probabilidade de apresentar problemas. Este \u00e9 o papel da valida\u00e7\u00e3o no desenvolvimento do projeto de um produto, e por isso tem vital import\u00e2ncia.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.altus.com.br\/upload\/htmleditor\/perfil-roberto.jpg\" alt=\"Roberto Martiny, Projetista de Produtos e Sistemas\" border=\"0\" align=\"left\" title=\"Roberto Martiny, Projetista de Produtos e Sistemas\" style=\"padding-right: 20px;\"><\/p>\n<div>\n<p style=\"padding-top:10px; text-align:left\"><strong>About the author<\/strong><br \/>Roberto Martiny entrou para a fam\u00edlia Altus em 2003 como estagi\u00e1rio e, desde ent\u00e3o, vem desenvolvendo sua trajet\u00f3ria na equipe de P&#038;D. Hoje, ocupa a posi\u00e7\u00e3o de Projetista de Produtos e Sistemas e atua no processo de valida\u00e7\u00e3o dos produtos comercializados pela empresa.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Na Perspectiva desta semana, Roberto Martiny, Projetista de Produtos e Sistemas, fala sobre a import\u00e2ncia do processo de valida\u00e7\u00e3o para projetos de produtos.<\/p>","protected":false},"author":5,"featured_media":7235,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[480,478,132,479,457,477],"class_list":["post-7234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-perspectivas","tag-desenvolvimento-de-software","tag-pd","tag-projetos","tag-software","tag-teste","tag-validacao"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.altus.com.br\/en\/wp-json\/wp\/v2\/posts\/7234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.altus.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.altus.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.altus.com.br\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.altus.com.br\/en\/wp-json\/wp\/v2\/comments?post=7234"}],"version-history":[{"count":1,"href":"https:\/\/www.altus.com.br\/en\/wp-json\/wp\/v2\/posts\/7234\/revisions"}],"predecessor-version":[{"id":8098,"href":"https:\/\/www.altus.com.br\/en\/wp-json\/wp\/v2\/posts\/7234\/revisions\/8098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.altus.com.br\/en\/wp-json\/wp\/v2\/media\/7235"}],"wp:attachment":[{"href":"https:\/\/www.altus.com.br\/en\/wp-json\/wp\/v2\/media?parent=7234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.altus.com.br\/en\/wp-json\/wp\/v2\/categories?post=7234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.altus.com.br\/en\/wp-json\/wp\/v2\/tags?post=7234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}